{"id":47274,"date":"2021-03-05T10:13:57","date_gmt":"2021-03-05T10:13:57","guid":{"rendered":"https:\/\/www.dewetron.com\/news\/die-instrumente-in-oxygen-ueberblick-1\/"},"modified":"2025-03-03T14:19:05","modified_gmt":"2025-03-03T14:19:05","slug":"die-instrumente-in-oxygen-ueberblick-1","status":"publish","type":"post","link":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/","title":{"rendered":"Die Instrumente in OXYGEN &#8211; \u00dcberblick Teil I von II"},"content":{"rendered":"<div id=\"\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2><\/h2>\n          <div class=\"content-size-normal\">\n            <p><a href=\"https:\/\/www.dewetron.com\/de\/produkte\/software\/oxygen-uebersicht\/\" target=\"_blank\" rel=\"noopener\">OXYGEN<\/a> &#8211; die intuitivste Messsoftware zur Datenerfassung und Analyse &#8211; ist f\u00fcr MesstechnikerInnen auf der ganzen Welt unverzichtbar geworden. Was klein begann, wurde schnell zur Go-to-L\u00f6sung f\u00fcr komplexe und umfassende Erfassungs- und Analyseaufgaben. Deshalb bietet DEWETRON nun eine breite Palette der verschiedensten Instrumente in OXYGEN an. Lesen Sie weiter, um einen ersten Eindruck zu bekommen, was die Software alles beinhaltet.<\/p>\n<p>&nbsp;<\/p>\n<h3>Instrumente in OXYGEN &#8211; \u00dcberblick Teil 1<\/h3>\n<p>Wenn Sie OXYGEN 5.4 verwenden, steht Ihnen eine Auswahl von 21 verschiedenen Instrumenten zur Verf\u00fcgung. In der folgenden Liste finden Sie einen schnellen \u00dcberblick \u00fcber alle verf\u00fcgbaren Instrumente in OXYGEN:<\/p>\n<ul>\n<li><a href=\"#1\">Analoganzeige (Analog Meter)<\/a><\/li>\n<li><a href=\"#2\">Digitalanzeige (Digital Meter)<\/a><\/li>\n<li><a href=\"#3\">Rekorder<\/a><\/li>\n<li><a href=\"#4\">Linienschreiber (Chart Recorder)<\/a><\/li>\n<li><a href=\"#5\">Balkenanzeige (Bar Meter)<\/a><\/li>\n<li><a href=\"#6\">Indikator<\/a><\/li>\n<li><a href=\"#7\">Tabelle (Table)<\/a><\/li>\n<li><a href=\"#8\">Bild (Image)<\/a><\/li>\n<li><a href=\"#9\">Text<\/a><\/li>\n<li><a href=\"#10\">Oszilloskop (Scope)<\/a><\/li>\n<\/ul>\n<p>Bitte beachten Sie, dass die Anzahl der Instrumente in OXYGEN je nach Software-Version unterschiedlich sein kann. Um Ihr OXYGEN auf die neueste Version zu aktualisieren, besuchen Sie bitte unseren <a href=\"https:\/\/ccc.dewetron.com\/Productlines\/view\/564af6b0-7628-4d66-b2f7-2d6bd9c49861\" target=\"_blank\" rel=\"noopener\">Download-Bereich im Customer Care Center<\/a>. Dar\u00fcber hinaus k\u00f6nnen Sie auch ein Upgrade durchf\u00fchren, um eine zus\u00e4tzliche Option zu erhalten (z.B. OXY-OPT-POWER-BASIC, OXY-OPT-POWER-ADVANCED, OXY-OPT-NET, etc.). Eine umfassende Liste der <a href=\"https:\/\/www.dewetron.com\/de\/produkte\/software\/oxygen-uebersicht\/\" target=\"_blank\" rel=\"noopener\">OXYGEN-Optionen finden Sie auf unserer Website<\/a>. Und wenn Sie noch kein OXYGEN-User sind, die Software aber gerne ausprobieren m\u00f6chten, laden Sie sich einfach unsere <a href=\"https:\/\/ccc.dewetron.com\/Productlines\/view\/564af6b0-7628-4d66-b2f7-2d6bd9c49861\" target=\"_blank\" rel=\"noopener\">kostenlose Testversion<\/a> herunter. Der Einfachheit zuliebe, haben wir uns entschlossen, diesen Beitrag in zwei Teile zu unterteilen. Daher finden Sie in diesem Blogpost Abbildungen von zehn Instrumenten und weitere in <a href=\"https:\/\/www.dewetron.com\/de\/news\/structure-of-oxygen-instruments-part-2\/\">diesem Blogpost<\/a>.<\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"1\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Analoganzeige (Analog Meter)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>In Abbildung 1 sehen Sie eine Darstellung der Analoganzeige von DEWETRON. \u00c4hnlich wie andere Instrumente in OXYGEN k\u00f6nnen Sie verschiedene Eigenschaften (\u00fcber das Instrumenteneigentschaften-Men\u00fc) anpassen. Neben verschiedenen Visualisierungsoptionen bei der Anzeige k\u00f6nnen Sie die analoge Darstellung Ihrer Messdaten weiter anpassen. Eine \u00dcbersicht \u00fcber die verf\u00fcgbaren Einstellungen (Bereich, Grenzwerte, Anzeigewert, Stil und Ebene) sehen Sie auf der rechten Seite von Abbildung 1.<\/p>\n<p>Sie k\u00f6nnen bis zu 96 Kan\u00e4le einer einzelnen Analoganzeige zuweisen.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20280 \" title=\"01_AnalogMeter\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/01_AnalogMeter.jpg\" alt=\"Screenshot der Analoganzeige - eines der Instrumente in OXYGEN\" width=\"815\" height=\"484\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 1<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"2\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Digitalanzeige (Digital Meter)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Die Digitalanzeige gibt AnwenderInnen schnell und einfach einen dashboardartigen \u00dcberblick \u00fcber den Messkanal. Dar\u00fcber hinaus k\u00f6nnen Sie die Funktionen des Instruments weiter ausbauen. So k\u00f6nnen Sie z. B. die Grenzwerte (z. B. \u00c4nderung der Farbe auf Basis der Grenzwerte), das Zahlenformat und die Genauigkeit (d. h. die Anzahl der Dezimalstellen) einstellen. Au\u00dferdem k\u00f6nnen Sie eine Mindestanzahl von Ziffern festlegen und den Wertetyp (Istwert, Mittelwert, RMS, ACRMS, Min, Max, Spitze-Spitze-Wert) ausw\u00e4hlen.\u00a0 Au\u00dferdem k\u00f6nnen Sie den Stil (Hintergrund, Anzahl der Spalten, Rahmen) des Instruments anpassen und Ihre Instrumente in Ebenen anordnen.<\/p>\n<p>Wie bei der Analoganzeige k\u00f6nnen auch bei der Digitalanzeige bis zu 96 Kan\u00e4le angezeigt werden.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-20337 aligncenter\" title=\"01_AnalogMeter2\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/01_AnalogMeter2.jpg\" alt=\"Digitalanzeige in OXYGEN\" width=\"813\" height=\"441\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 2<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"3\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Rekorder<\/h2>\n          <div class=\"content-size-normal\">\n            <p>DEWETRONs Rekordern ist ein Messschreiber, erweitert um einige n\u00fctzliche Einstellungen und Funktionen. In den Instrumenteneigenschaften k\u00f6nnen Sie z. B. die Zeitachse modifizieren, wodurch sich das Format der X-Achse \u00e4ndert (Autozeit, Absolutzeit, Relativzeit). Dar\u00fcber hinaus k\u00f6nnen Sie nat\u00fcrlich auch den Bereich der Werteachse (Y-Achse) festlegen. Au\u00dferdem k\u00f6nnen \u00fcber die Instrumenteneigenschaften viele weitere Einstellm\u00f6glichkeiten in Bezug auf Skalierung, Cursor, Marker usw. vorgenommen werden. <a href=\"https:\/\/ccc.dewetron.com\/Productlines\/view\/564af6b0-7628-4d66-b2f7-2d6bd9c49861\" target=\"_blank\" rel=\"noopener\">Weitere Informationen dazu finden Sie in unserem Software Manual.<\/a><\/p>\n<p>Tipp: Sie k\u00f6nnen bis zu acht Kan\u00e4le in nur einem Rekorder anzeigen lassen.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20334 aligncenter\" title=\"02_Recorder2\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/02_Recorder2.jpg\" alt=\"DEWETRONs Rekorder\" width=\"814\" height=\"440\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 3<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"4\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Linienschreiber (Chart Recorder)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Mit unserem Linienschreiber erhalten AnwenderInnen die M\u00f6glichkeit, mehrere separate Charts untereinander zu visualisieren. Der Linienschreiber bietet die gleichen Eigenschaften und Analysen wie der Rekorder. Sie k\u00f6nnen allerdings sogar bis zu 16 Kan\u00e4le mit einem einzigen Linienschreiber darstellen.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-20327 aligncenter\" title=\"04_ChartRecorder\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/04_ChartRecorder2.jpg\" alt=\"Ein Screenshot eines Linienschreibers\" width=\"815\" height=\"443\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 4<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"5\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Balkenanzeige (Bar Meter)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Die Balkenanzeige ist eine zus\u00e4tzliche M\u00f6glichkeit, um den Messwert eines Kanals anzuzeigen. \u00c4hnlich wie andere Instrumente in OXYGEN kann auch Balkenanzeige \u00fcber die Eigenschaften angepasst werden. Dabei k\u00f6nnen Sie Einstellungen bez\u00fcglich des Bereiches (auch Auto-Bereich verf\u00fcgbar), der Grenzwerte, des Anzeigewerts, des Stils und der Instrumentenebenen \u00e4ndern. Sie k\u00f6nnen bis zu 96 Kan\u00e4le einer einzigen Balkenanzeige zuweisen.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20330 aligncenter\" title=\"05_BarMeter\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/05_BarMeter2.jpg\" alt=\"Screenshot der Balkenanzeige\" width=\"816\" height=\"443\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 5<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"6\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Indikator<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Den \u00dcberblick \u00fcber den Messstatus zu behalten, ist entscheidend. Deshalb haben wir den Indikator entwickelt. Dieses Instrument \u00e4ndert seine Farbe in Abh\u00e4ngigkeit vom Wert des Kanals. Dazu geh\u00f6rt auch die Definition von Grenzwerten, bei denen AnwenderInnen Farben z. B. f\u00fcr den oberen und unteren Grenzwert festlegen k\u00f6nnen. Dadurch k\u00f6nnen Sie wiederum die Anzeigewerte nach Ihren Bed\u00fcrfnissen ver\u00e4ndern und bis zu 96 Kan\u00e4le in nur einem Indikator zusammenfassen. Wie man einen Indikator erstellt, erkl\u00e4ren wir im Video unterhalb (Video 1).<br \/>\n&nbsp;<\/p>\n<div style=\"text-align: center;\">\n<p style=\"text-align: center;\"> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSBzcmM9Imh0dHBzOi8vd3d3LnlvdXR1YmUuY29tL2VtYmVkLy1Rc0w0N2FfNlVNIiB3aWR0aD0iNTYwIiBoZWlnaHQ9IjM0MCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iYWxsb3dmdWxsc2NyZWVuIj48c3BhbiBkYXRhLW1jZS10eXBlPSJib29rbWFyayIgc3R5bGU9ImRpc3BsYXk6IGlubGluZS1ibG9jazsgd2lkdGg6IDBweDsgb3ZlcmZsb3c6IGhpZGRlbjsgbGluZS1oZWlnaHQ6IDA7IiBjbGFzcz0ibWNlX1NFTFJFU19zdGFydCI+77u\/PC9zcGFuPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.dewetron.com\/app\/uploads\/borlabs-cookie\/1\/yt_-QsL47a_6UM_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>YouTube<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf die Schaltfl\u00e4che unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Mehr Informationen<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <\/div> <\/div><\/div><\/p>\n<p style=\"text-align: center;\"><em>Video 1<\/em><\/p>\n<\/div>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"7\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Tabelle (Table)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Mit dem Tabelleninstrument k\u00f6nnen Sie die Messdaten von bis zu acht Kan\u00e4len in Tabellenform darstellen. Dabei legt OXYGEN eine Spalte f\u00fcr die Zeitachse an und ordnet jedem Signal eine eigene Spalte zu.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20313 size-full\" title=\"06_Table\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/06_Table.jpg\" alt=\"Tabellen in OXYGEN\" width=\"610\" height=\"326\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 6<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"8\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Bild (Image)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Um alle Ihre Daten in nur einem Bericht zusammenzufassen, k\u00f6nnen Bilder ein wichtiger Faktor werden. OXYGEN bietet Ihnen daher die M\u00f6glichkeit, ein beliebiges Bild (z.B. das Logo Ihres Kunden oder ein Foto des Pr\u00fcflings) einfach zu integrieren. Um diese Funktion zu nutzen, k\u00f6nnen Sie den Pfad \u00fcber die Ger\u00e4teeigenschaften ausw\u00e4hlen und nach der gew\u00fcnschten Bilddatei suchen. Au\u00dferdem stehen verschiedene Optionen zur Verf\u00fcgung, um das Bild zu ver\u00e4ndern (z. B. F\u00fcllmodus, Stil, Ebene). Dar\u00fcber hinaus k\u00f6nnen Sie auch Bilder (*.jpegs oder *.pngs) aus dem Windows-Explorer in den OXYGEN-Messbildschirm kopieren und einf\u00fcgen. Verwenden Sie dazu einfach die Tastenkombinationen CTRL+C und CTRL+V.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20324 aligncenter\" title=\"07_Image2\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/07_Image2.jpg\" alt=\"Bild Instrumente in OXYGEN\" width=\"819\" height=\"445\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 7<\/em><\/p>\n<p>&nbsp;<br \/>\nUm alle Ihre Daten in nur einem Bericht zusammenzufassen, k\u00f6nnen Bilder ein wichtiger Faktor werden. OXYGEN bietet Ihnen daher die M\u00f6glichkeit, ein beliebiges Bild (z.B. das Logo Ihres Kunden oder ein Foto des Pr\u00fcflings) einfach zu integrieren. Um diese Funktion zu nutzen, k\u00f6nnen Sie den Pfad \u00fcber die Ger\u00e4teeigenschaften ausw\u00e4hlen und nach der gew\u00fcnschten Bilddatei suchen. Au\u00dferdem stehen verschiedene Optionen zur Verf\u00fcgung, um das Bild zu ver\u00e4ndern (z. B. F\u00fcllmodus, Stil, Ebene). Dar\u00fcber hinaus k\u00f6nnen Sie auch Bilder (*.jpegs oder *.pngs) aus dem Windows-Explorer in den OXYGEN-Messbildschirm kopieren und einf\u00fcgen. Verwenden Sie dazu einfach die Tastenkombinationen CTRL+C und CTRL+V.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20324 aligncenter\" title=\"07_Image2\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/07_Image2.jpg\" alt=\"Bild Instrumente in OXYGEN\" width=\"819\" height=\"445\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 7<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"9\" class=\"wp-block-text-columns margin-bottom-small\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Text<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Die Textfunktion erm\u00f6glicht es, benutzerdefinierte Textelemente direkt auf dem Messbildschirm zu erstellen. Das hei\u00dft, Sie k\u00f6nnen Headerdaten, Datum, Uhrzeit und die Messzeit innerhalb eines Textfeldes anzeigen. F\u00fcr eine genauere<a href=\"https:\/\/youtu.be\/zh9SZB5WzTA\" target=\"_blank\" rel=\"noopener\"> Beschreibung der Anzeige von Headerdaten im Textfeld empfehlen wir dieses Video<\/a>. Das Textinstrument bietet wieder mehrere Optionen, z. B. k\u00f6nnen Sie die Farbe des Textes \u00e4ndern, fett oder kursiv formatieren und die horizontale sowie vertikale Ausrichtung anpassen.<br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20318 aligncenter\" title=\"08_Text2\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/08_Text2.jpg\" alt=\"Text\" width=\"813\" height=\"440\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 8<\/em><\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"10\" class=\"wp-block-text-columns margin-bottom-none\n      \">\n  <div class=\"container\">\n    <div class=\"row justify-content-center\">\n              <div class=\"col-12\">\n          <h2>Oszilloskop (Scope)<\/h2>\n          <div class=\"content-size-normal\">\n            <p>Mit Hilfe dieses Instruments erm\u00f6glicht OXYGEN AnwenderInnen, den Umfang einer Messung mit bis zu acht Kan\u00e4len zu analysieren. Die Flankenauswahl erlaubt es AnwenderInnen, Signale auf eine steigende oder fallende Flanke zu triggern, mit der M\u00f6glichkeit, einen Pegel frei zu definieren. Zus\u00e4tzlich steht die Option einer Hysterese zur Verf\u00fcgung, um ein Triggerereignis aufgrund von Rauschen um den Triggerpegel zu vermeiden. <a href=\"https:\/\/ccc.dewetron.com\/Productlines\/view\/564af6b0-7628-4d66-b2f7-2d6bd9c49861\" target=\"_blank\" rel=\"noopener\">Weitere Informationen dazu finden Sie in unserem OXYGEN Manual.<\/a><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20321 size-full\" title=\"09_Scope\" src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/09\/09_Scope.jpg\" alt=\"Oszilloskop in OXYGEN\" width=\"602\" height=\"359\" \/><\/p>\n<p style=\"text-align: center;\"><em>Abbildung 9<\/em><\/p>\n<p>&nbsp;<\/p>\n\n          <\/div>\n        <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-claim-links-gray margin-bottom-none\">\n  <div class=\"container-fluid bg-container py-7 bg-darkgray\">\n    <div class=\"container position-relative\">\n      <div class=\"claim col-12 col-lg-8 offset-lg-2 text-center text-light\">\n                  <h3 class=\"h3 text-uppercase\">LERNEN SIE UNSERE OXYGEN MESSSOFTWARE BESSER KENNEN:<\/h3>\n                                  <div class=\"link-button d-flex flex-wrap mt-4 justify-content-center gap-4\">\n                          <a class=\"dewetron-btn\" href=\"https:\/\/www.dewetron.com\/de\/produkte\/software\/oxygen-uebersicht\/\" target=\"_blank\">\n          \n      <span>MEHR ERFAHREN<\/span>\n      <\/a>\n                                      <a class=\"dewetron-btn\" href=\"https:\/\/www.dewetron.com\/de\/know-how-center\/video-tutorials\/\" target=\"_blank\">\n          \n      <span>OXYGEN VIDEO-TUTORIALS<\/span>\n      <\/a>\n                                      <a class=\"dewetron-btn\" href=\"https:\/\/www.dewetron.com\/de\/know-how-center\/webinare\/\" target=\"_blank\">\n          \n      <span>OXYGEN WEBINARE<\/span>\n      <\/a>\n                      <\/div>\n              <\/div>\n    <\/div>\n    <div class=\"triangle-left\">\n      <svg width=\"473\" height=\"469\" viewBox=\"0 0 473 469\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M323.984 352.833H79.0486L13.0728 467.099V468.52H390.784L323.984 352.833Z\" fill=\"#B0B0AF\"\/>\n<path d=\"M134.967 0L-68 351.55L-2.02418 465.84L-0.810036 466.55L268.545 0H134.967Z\" fill=\"#B0B0AF\"\/>\n<path d=\"M472.154 352.833L275.853 12.8511L209.053 128.515L405.354 468.52L472.154 352.833Z\" fill=\"#B0B0AF\"\/>\n<\/svg>    <\/div>\n    <div class=\"triangle-right\">\n      <svg width=\"462\" height=\"644\" viewBox=\"0 0 462 644\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M538.396 484.622H201.974L111.355 641.569V643.52H630.148L538.396 484.622Z\" fill=\"#B0B0AF\"\/>\n<path d=\"M278.779 0L0 482.86L90.6189 639.839L92.2865 640.814L462.251 0H278.779Z\" fill=\"#B0B0AF\"\/>\n<path d=\"M741.911 484.622L472.288 17.6514L380.537 176.518L650.159 643.52L741.911 484.622Z\" fill=\"#B0B0AF\"\/>\n<\/svg>    <\/div>\n  <\/div>\n<\/div>\n\n\n<div id=\"\" class=\"wp-block-news-slider margin-bottom-none\">\n  <div class=\"container-fluid bg-lightgray py-lg-8 py-6\">\n    <div class=\"header-wrapper container\">\n      <div class=\"row flex-row flex-wrap\">\n        <div class=\"col-12 col-lg-6\">\n          <div class=\"content-wrapper\">\n            <div class=\"content\">\n                                            <h2 class=\"h2 text-uppercase mb-5\">Weitere Neuigkeiten &#038; Whitepaper<\/h2>\n                          <\/div>\n          <\/div>\n        <\/div>\n        <div class=\"col-lg-6 d-none d-lg-grid link\">\n                      <a class=\"dewetron-btn mb-5\" href=\"https:\/\/www.dewetron.com\/de\/know-how-center\/newsroom\/\" target=\"\">\n          Alle News\n      <span><\/span>\n      <\/a>\n                  <\/div>\n      <\/div>\n      <div class=\"row news-wrapper\">\n        <div class=\"news-slider swiper\">\n          <div class=\"swiper-wrapper\">\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/structure-of-oxygen-instruments-part-2\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header-oxygen-instruments.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Software-Info<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Die Instrumente in OXYGEN &#8211; \u00dcberblick TEil II\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/10-fragen-ueber-unsere-messsoftware\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_10-questions-about-oxygen_.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Software-Info<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      10 Fragen \u00fcber OXYGEN &#8211; unsere Messsoftware\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/oxygen-power-option\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_power-option.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Software-Info<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Die OXYGEN Power-Option: alles was zu wissen ist\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/undestanding-time-modern-systems\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2026\/01\/Header-scaled.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Whitepaper<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Undestanding Time in Modern Systems\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/das-verstandnis-von-zeit-in-modernen-systemen-2\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2026\/01\/Header-scaled.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Uncategorized<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Das Verst\u00e4ndnis von Zeit in modernen Systemen\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/das-verstandnis-von-zeit-in-modernen-systemen\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2026\/01\/Header-scaled.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Uncategorized<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Das Verst\u00e4ndnis von Zeit in modernen Systemen\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/dewetrons-litepa-der-leicht-integrierbare-standard-power-analyzer\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/06\/header_litepa_.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Hardware-Neuigkeiten<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      DEWETRONs LITE[PA]: Der leicht integrierbare Standard-Power Analyzer\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/eingangskanalspezifikationen\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2025\/06\/Header-input-specifications.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Whitepaper<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      7 Eingangskanalspezifikationen zur Bestimmung der Messgenauigkeit\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/dewetron-unterstuetzt-historischen-nasa-mission-artemis-ii-launch\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2026\/04\/dewetron-nasa-artemisII-launch.jpg\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Generelle Infos<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      DEWETRON unterst\u00fctzt historischen NASA-Mission Artemis II Launch\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                          <div class=\"news-card swiper-slide col-lg-4 col-12 bg-light \">\n                <a class=\"\" href=\"https:\/\/www.dewetron.com\/de\/news\/verteilte-messungen-mit-oxygen-net\/\" target=\"\">\n          <picture>\n        <img decoding=\"async\"\n        class=\"img-fluid aspect-4-3\" size=\"full\"\n        src=\"https:\/\/www.dewetron.com\/app\/uploads\/2026\/03\/OXYGEN-NET_Header.png\"\n        alt=\"\"\n        title=\"\"\n        loading=\"lazy\"\n                    onerror=\"this.src = 'https:\/\/www.dewetron.com\/app\/themes\/dewetron\/public\/images\/fallback.8952c5.jpg'\"\n            >\n<\/picture>\n                  <div class=\"card-content p-2\">\n                    <span class=\"category d-inline-flex\">Whitepaper<\/span>\n                    <h5 class=\"mb-2 mt-4 text-uppercase\">\n                      Verteilte Messungen mit OXYGEN-NET\n                    <\/h5>\n                                        <span class=\"read-more text-primary text-uppercase mt-4 d-block\">\n                      Mehr lesen\n                    <\/span>\n                  <\/div>\n      <span><\/span>\n      <\/a>\n              <\/div>\n                      <\/div>\n        <\/div>\n        <div class=\"swiper-button-custom swiper-button-prev-custom p-0\">\n            <svg width=\"89\" height=\"103\" viewBox=\"0 0 89 103\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M0 58.8001V44.2001L88.6 0.600098V17.8001L17.4 51.6001L88.6 85.2001V102.4L0 58.8001Z\" fill=\"#D4D4D4\"\/>\n<\/svg>        <\/div>\n        <div class=\"swiper-button-custom swiper-button-next-custom p-0\">\n            <svg width=\"89\" height=\"103\" viewBox=\"0 0 89 103\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M88.6 44.2001V58.8001L0 102.4V85.2001L71.2 51.4001L0 17.8001V0.600098L88.6 44.2001Z\" fill=\"#D4D4D4\"\/>\n<\/svg>        <\/div>\n      <\/div>\n      <div class=\"col-12 d-lg-none d-grid link text-cente mt-8\">\n                <a class=\"dewetron-btn\" href=\"https:\/\/www.dewetron.com\/de\/know-how-center\/newsroom\/\" target=\"\">\n          Alle News\n      <span><\/span>\n      <\/a>\n              <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr. <\/p>\n","protected":false},"author":2,"featured_media":42403,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[393],"tags":[],"class_list":["post-47274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-info-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die Instrumente in OXYGEN - \u00dcberblick Teil I von II - DEWETRON<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Instrumente in OXYGEN - \u00dcberblick Teil I von II\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\" \/>\n<meta property=\"og:site_name\" content=\"DEWETRON\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dewetron.gmbh\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-05T10:13:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-03T14:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1611\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bettina Dunst\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bettina Dunst\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\"},\"author\":{\"name\":\"Bettina Dunst\",\"@id\":\"https:\/\/www.dewetron.com\/de\/#\/schema\/person\/8f0457a73abffb512203296cd2a59159\"},\"headline\":\"Die Instrumente in OXYGEN &#8211; \u00dcberblick Teil I von II\",\"datePublished\":\"2021-03-05T10:13:57+00:00\",\"dateModified\":\"2025-03-03T14:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg\",\"articleSection\":[\"Software-Info\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\",\"url\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\",\"name\":\"Die Instrumente in OXYGEN - \u00dcberblick Teil I von II - DEWETRON\",\"isPartOf\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg\",\"datePublished\":\"2021-03-05T10:13:57+00:00\",\"dateModified\":\"2025-03-03T14:19:05+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage\",\"url\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg\",\"contentUrl\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg\",\"width\":1611,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dewetron.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Instrumente in OXYGEN &#8211; \u00dcberblick Teil I von II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dewetron.com\/de\/#website\",\"url\":\"https:\/\/www.dewetron.com\/de\/\",\"name\":\"DEWETRON\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dewetron.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dewetron.com\/de\/#organization\",\"name\":\"DEWETRON\",\"url\":\"https:\/\/www.dewetron.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.dewetron.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/08\/DEWETRON-logo-text-and-image.png\",\"contentUrl\":\"https:\/\/www.dewetron.com\/app\/uploads\/2024\/08\/DEWETRON-logo-text-and-image.png\",\"width\":900,\"height\":979,\"caption\":\"DEWETRON\"},\"image\":{\"@id\":\"https:\/\/www.dewetron.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dewetron.gmbh\",\"https:\/\/www.linkedin.com\/company\/dewetron\/\",\"https:\/\/www.instagram.com\/wearedewetron\/\",\"https:\/\/www.youtube.com\/channel\/UCE76NeVVgWF65etH8E1bOog\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dewetron.com\/de\/#\/schema\/person\/8f0457a73abffb512203296cd2a59159\",\"name\":\"Bettina Dunst\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g\",\"caption\":\"Bettina Dunst\"},\"url\":\"https:\/\/www.dewetron.com\/de\/news\/author\/bettina-dunst\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Instrumente in OXYGEN - \u00dcberblick Teil I von II - DEWETRON","description":"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/","og_locale":"de_DE","og_type":"article","og_title":"Die Instrumente in OXYGEN - \u00dcberblick Teil I von II","og_description":"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.","og_url":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/","og_site_name":"DEWETRON","article_publisher":"https:\/\/www.facebook.com\/dewetron.gmbh","article_published_time":"2021-03-05T10:13:57+00:00","article_modified_time":"2025-03-03T14:19:05+00:00","og_image":[{"width":1611,"height":600,"url":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg","type":"image\/jpeg"}],"author":"Bettina Dunst","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bettina Dunst","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#article","isPartOf":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/"},"author":{"name":"Bettina Dunst","@id":"https:\/\/www.dewetron.com\/de\/#\/schema\/person\/8f0457a73abffb512203296cd2a59159"},"headline":"Die Instrumente in OXYGEN &#8211; \u00dcberblick Teil I von II","datePublished":"2021-03-05T10:13:57+00:00","dateModified":"2025-03-03T14:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/"},"wordCount":10,"publisher":{"@id":"https:\/\/www.dewetron.com\/de\/#organization"},"image":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg","articleSection":["Software-Info"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/","url":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/","name":"Die Instrumente in OXYGEN - \u00dcberblick Teil I von II - DEWETRON","isPartOf":{"@id":"https:\/\/www.dewetron.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage"},"image":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg","datePublished":"2021-03-05T10:13:57+00:00","dateModified":"2025-03-03T14:19:05+00:00","description":"Erfahren Sie mehr \u00fcber die wichtigsten Funktionen der OXYGEN Messsoftware wie die Analog- und Digitalanzeige, Rekorder und vieles mehr.","breadcrumb":{"@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#primaryimage","url":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg","contentUrl":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/10\/header_instruments-oxygen.jpg","width":1611,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.dewetron.com\/de\/news\/die-instrumente-in-oxygen-ueberblick-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dewetron.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die Instrumente in OXYGEN &#8211; \u00dcberblick Teil I von II"}]},{"@type":"WebSite","@id":"https:\/\/www.dewetron.com\/de\/#website","url":"https:\/\/www.dewetron.com\/de\/","name":"DEWETRON","description":"","publisher":{"@id":"https:\/\/www.dewetron.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dewetron.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.dewetron.com\/de\/#organization","name":"DEWETRON","url":"https:\/\/www.dewetron.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.dewetron.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/08\/DEWETRON-logo-text-and-image.png","contentUrl":"https:\/\/www.dewetron.com\/app\/uploads\/2024\/08\/DEWETRON-logo-text-and-image.png","width":900,"height":979,"caption":"DEWETRON"},"image":{"@id":"https:\/\/www.dewetron.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dewetron.gmbh","https:\/\/www.linkedin.com\/company\/dewetron\/","https:\/\/www.instagram.com\/wearedewetron\/","https:\/\/www.youtube.com\/channel\/UCE76NeVVgWF65etH8E1bOog"]},{"@type":"Person","@id":"https:\/\/www.dewetron.com\/de\/#\/schema\/person\/8f0457a73abffb512203296cd2a59159","name":"Bettina Dunst","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf0df50dc5d25d9ea432c4399e038ca4e0ebeaae9b9c18bd51f6939f36a5a0eb?s=96&d=mm&r=g","caption":"Bettina Dunst"},"url":"https:\/\/www.dewetron.com\/de\/news\/author\/bettina-dunst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/posts\/47274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/comments?post=47274"}],"version-history":[{"count":4,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/posts\/47274\/revisions"}],"predecessor-version":[{"id":56400,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/posts\/47274\/revisions\/56400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/media\/42403"}],"wp:attachment":[{"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/media?parent=47274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/categories?post=47274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dewetron.com\/de\/wp-json\/wp\/v2\/tags?post=47274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}